{"id":6322,"date":"2023-04-20T17:31:24","date_gmt":"2023-04-20T21:31:24","guid":{"rendered":"https:\/\/cssphiladelphia.org\/apoyo-para-padres-e-hijos-en-la-casa-del-carmen\/"},"modified":"2023-04-20T17:31:24","modified_gmt":"2023-04-20T21:31:24","slug":"apoyo-para-padres-e-hijos-en-la-casa-del-carmen","status":"publish","type":"post","link":"https:\/\/cssphiladelphia.org\/es\/apoyo-para-padres-e-hijos-en-la-casa-del-carmen\/","title":{"rendered":"Apoyo para Padres e Hijos en la Casa del Carmen"},"content":{"rendered":"<p>En una tarde soleada y h\u00fameda en Julio, madres, padres, abuelos, y ni\u00f1os del Norte de Filadelfia se reunieron en la Casa del Carmen Centro de Servios para la Familia para el \u00abFestival de Verano\u00bb, una celebraci\u00f3n anual para las familias.<\/p>\n<p><a href=\"https:\/\/cssphiladelphia.org\/prenatal-and-parenting-programs\/\">El programa de Beautiful Beginnings <\/a>de formaci\u00f3n para los padres en la Casa del Carmen acogi\u00f3 la tarde de comida y diversi\u00f3n. El acontecimiento fue un descanso bienvenido de eventos remotos y \u00abreuniones\u00bb digitales tan comunes a trav\u00e9s de la pandemia.<\/p>\n<p>Los vecinos disfrutaron de cosas favoritas de Philly: hoagies, pretzels suaves, y helado. Dice Jenny Munguia, BA, BSW, Maestra Prenatal y de Crianza en Casa del Carmen, \u201cEl festival de verano es una manera de reunir a la gente, y aliviar el estr\u00e9s de estar solo. Para que la gente puedan conocer a sus vecinos\u00bb.<\/p>\n<h1>Educaci\u00f3n sobre Embarazo y Crianza<\/h1>\n<p><img decoding=\"async\" class=\"lazyload wp-image-5893 alignleft\" src=\"https:\/\/cssphiladelphia.org\/wp-content\/uploads\/2022\/08\/pexels-julia-m-cameron-4145190-scaled.jpg\" data-orig-src=\"https:\/\/cssphiladelphia.org\/wp-content\/uploads\/2022\/08\/pexels-julia-m-cameron-4145190-scaled.jpg\" alt=\"\" width=\"290\" height=\"194\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27290%27%20height%3D%27194%27%20viewBox%3D%270%200%20290%20194%27%3E%3Crect%20width%3D%27290%27%20height%3D%27194%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/cssphiladelphia.org\/wp-content\/uploads\/2022\/08\/pexels-julia-m-cameron-4145190-200x133.jpg 200w, https:\/\/cssphiladelphia.org\/wp-content\/uploads\/2022\/08\/pexels-julia-m-cameron-4145190-300x200.jpg 300w, https:\/\/cssphiladelphia.org\/wp-content\/uploads\/2022\/08\/pexels-julia-m-cameron-4145190-400x267.jpg 400w, https:\/\/cssphiladelphia.org\/wp-content\/uploads\/2022\/08\/pexels-julia-m-cameron-4145190-600x400.jpg 600w, https:\/\/cssphiladelphia.org\/wp-content\/uploads\/2022\/08\/pexels-julia-m-cameron-4145190-768x513.jpg 768w, https:\/\/cssphiladelphia.org\/wp-content\/uploads\/2022\/08\/pexels-julia-m-cameron-4145190-800x534.jpg 800w, https:\/\/cssphiladelphia.org\/wp-content\/uploads\/2022\/08\/pexels-julia-m-cameron-4145190-1024x683.jpg 1024w, https:\/\/cssphiladelphia.org\/wp-content\/uploads\/2022\/08\/pexels-julia-m-cameron-4145190-1200x801.jpg 1200w, https:\/\/cssphiladelphia.org\/wp-content\/uploads\/2022\/08\/pexels-julia-m-cameron-4145190-1536x1025.jpg 1536w, https:\/\/cssphiladelphia.org\/wp-content\/uploads\/2022\/08\/pexels-julia-m-cameron-4145190-scaled.jpg 2560w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 290px) 100vw, 290px\" \/>Aislamiento social, y el estr\u00e9s que lo acompa\u00f1a, es demasiado com\u00fan en familias con bebes y ni\u00f1os peque\u00f1os. Catholic Social Services en Casa del Carmen ayuda a minimizar el aislamiento a trav\u00e9s de clases sobre el embarazo y crianza. Las clases y otros eventos y servicios conectan a nuevos padres y futuras madres y padres, y ayudan a construir comunidades cercanas y solidarias.<\/p>\n<p>Casa del Carmen est\u00e1 en North Philadelphia en 4400 N Reese Street. El centro presta servicios a la comunidad latina e hispanoparlante del norte de Filadelfia desde 1954. Su personal son culturalmente y ling\u00fc\u00edsticamente competentes y ayudan a las familias del barrio a vivir sus mejores vidas.<\/p>\n<p>El centro del vecindario ofrece un programa integral de alfabetizaci\u00f3n familiar, que incluye educaci\u00f3n sobre embarazo y crianza, salud, salud mental, conocimientos financieros y asistencia con la educaci\u00f3n temprana.<\/p>\n<p>En este lugar, tambi\u00e9n se ofrecen servicios de emergencia para asistencia con documentos, alquiler, hipoteca y servicios p\u00fablicos (sujeto a la disponibilidad de fondos). Tambi\u00e9n disponible son alimentos y pa\u00f1ales de emergencia, art\u00edculos para beb\u00e9s, y un punto de distribuci\u00f3n de productos de higiene femenina.<\/p>\n<p>Munguia, una maestra entrenada en crianza, ense\u00f1a clases de crianza dos veces a la semana los Lunes y los Jueves de las 10AM-12 mediod\u00eda. Adicionalmente, lleva clases sobre el embarazo los Lunes de la 1-2P.M.<\/p>\n<h1>Recursos Comunitarios para Familias<\/h1>\n<p><img decoding=\"async\" class=\"lazyload size-medium wp-image-5907 alignleft\" src=\"https:\/\/cssphiladelphia.org\/wp-content\/uploads\/2022\/08\/casa-del-carmen-blog-aug-22-300x200.jpg\" data-orig-src=\"https:\/\/cssphiladelphia.org\/wp-content\/uploads\/2022\/08\/casa-del-carmen-blog-aug-22-300x200.jpg\" alt=\"casa del carmen catholic social services\" width=\"300\" height=\"200\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27300%27%20height%3D%27200%27%20viewBox%3D%270%200%20300%20200%27%3E%3Crect%20width%3D%27300%27%20height%3D%27200%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/cssphiladelphia.org\/wp-content\/uploads\/2022\/08\/casa-del-carmen-blog-aug-22-200x133.jpg 200w, https:\/\/cssphiladelphia.org\/wp-content\/uploads\/2022\/08\/casa-del-carmen-blog-aug-22-300x200.jpg 300w, https:\/\/cssphiladelphia.org\/wp-content\/uploads\/2022\/08\/casa-del-carmen-blog-aug-22-400x267.jpg 400w, https:\/\/cssphiladelphia.org\/wp-content\/uploads\/2022\/08\/casa-del-carmen-blog-aug-22-600x400.jpg 600w, https:\/\/cssphiladelphia.org\/wp-content\/uploads\/2022\/08\/casa-del-carmen-blog-aug-22-768x512.jpg 768w, https:\/\/cssphiladelphia.org\/wp-content\/uploads\/2022\/08\/casa-del-carmen-blog-aug-22-800x533.jpg 800w, https:\/\/cssphiladelphia.org\/wp-content\/uploads\/2022\/08\/casa-del-carmen-blog-aug-22-1024x683.jpg 1024w, https:\/\/cssphiladelphia.org\/wp-content\/uploads\/2022\/08\/casa-del-carmen-blog-aug-22-1200x800.jpg 1200w, https:\/\/cssphiladelphia.org\/wp-content\/uploads\/2022\/08\/casa-del-carmen-blog-aug-22-1536x1024.jpg 1536w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 300px) 100vw, 300px\" \/>Sobre el programa, Munguia a\u00f1ade, \u00abTenemos una poblaci\u00f3n diversa con gente de M\u00e9xico, Guatemala, Honduras, la Rep\u00fablica Dominicana, Ecuador, Puerto Rico, y Hait\u00ed. Educamos a nuestros clientes sobre la crianza y recursos comunitarios que incluyen puntos de distribuci\u00f3n de alimentos y pa\u00f1ales, cunas, programas de asientos de carros, utilidades, y asistencia para el alquiler.\u00bb<\/p>\n<p>Anteriormente en persona, las clases de crianza ahora se llevan por Internet. Clases en Zoom permiten tener una poblaci\u00f3n mas grande de participantes. Residentes de South Philadelphia, Upper Darby, Northeast Philadelphia, Southwest and North Philadelphia pueden acceder las clases por Internet sin tener que salir de casa.<\/p>\n<p>Antes de la pandemia, cuando las clases eran en persona, todas eran biling\u00fce. Con el advenimiento de la instrucci\u00f3n remota, clases de un solo idioma resultaron ser mas efectivas para todos los participantes.<\/p>\n<p>Clases separadas ahora son ofrecidas para participantes en Espa\u00f1ol y en Ingles. Esta oportunidad \u00fanica en la ciudad de Filadelfia hacen las clases muy populares. Muchas veces hay una lista de espera para poder atender.<\/p>\n<p>El curr\u00edculo de la clase est\u00e1 basado en <a href=\"https:\/\/www.nurturingparenting.com\/\">Nurturing Parenting Program<\/a>, el <a href=\"https:\/\/strengtheningfamiliesprogram.org\/\">Strengthening Families Program<\/a>, y <a href=\"https:\/\/www.dhs.pa.gov\/Services\/Mental-Health-In-PA\/Pages\/ACT.aspx\">ACT Program<\/a>. Todos tienen un curr\u00edculo basado en evidencia que enfoca habilidades positivas de crianza. Est\u00e1n dise\u00f1ados para fomentar conductas de crianza, fortalecer las relaciones familiares, y mejorar la comunicaci\u00f3n entre todos los miembros de la familia.<\/p>\n<h1>Preparaci\u00f3n para la Llegada del Beb\u00e9<\/h1>\n<p><img decoding=\"async\" class=\"lazyload size-medium wp-image-5909 alignleft\" src=\"https:\/\/cssphiladelphia.org\/wp-content\/uploads\/2022\/08\/baby-diapering-300x200.jpg\" data-orig-src=\"https:\/\/cssphiladelphia.org\/wp-content\/uploads\/2022\/08\/baby-diapering-300x200.jpg\" alt=\"catholic social services pregnancy support\" width=\"300\" height=\"200\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%27300%27%20height%3D%27200%27%20viewBox%3D%270%200%20300%20200%27%3E%3Crect%20width%3D%27300%27%20height%3D%27200%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/cssphiladelphia.org\/wp-content\/uploads\/2022\/08\/baby-diapering-200x133.jpg 200w, https:\/\/cssphiladelphia.org\/wp-content\/uploads\/2022\/08\/baby-diapering-300x200.jpg 300w, https:\/\/cssphiladelphia.org\/wp-content\/uploads\/2022\/08\/baby-diapering-400x267.jpg 400w, https:\/\/cssphiladelphia.org\/wp-content\/uploads\/2022\/08\/baby-diapering-600x400.jpg 600w, https:\/\/cssphiladelphia.org\/wp-content\/uploads\/2022\/08\/baby-diapering-768x512.jpg 768w, https:\/\/cssphiladelphia.org\/wp-content\/uploads\/2022\/08\/baby-diapering-800x533.jpg 800w, https:\/\/cssphiladelphia.org\/wp-content\/uploads\/2022\/08\/baby-diapering-1024x683.jpg 1024w, https:\/\/cssphiladelphia.org\/wp-content\/uploads\/2022\/08\/baby-diapering-1200x800.jpg 1200w, https:\/\/cssphiladelphia.org\/wp-content\/uploads\/2022\/08\/baby-diapering-1536x1024.jpg 1536w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 300px) 100vw, 300px\" \/>Clases y talleres continuas cubren el cuidado b\u00e1sico bebes y ni\u00f1os. Temas incluyen un sue\u00f1o seguro y amamantamiento y hasta expectativas en la sala de parto y el tiempo del ba\u00f1o.<\/p>\n<p>Al completar cada clase de habilidades de crianza, los participantes obtienen un certificado de finalizaci\u00f3n y una tarjeta de regalo con $50.00. Munguia dice, \u201cTambi\u00e9n proveemos educaci\u00f3n a nuestros clientes sobre recursos comunitarios que incluyen puntos de distribuci\u00f3n de alimentos y pa\u00f1ales, cunas, programas de asientos de carros, utilidades, y asistencia para el alquiler.\u00bb<\/p>\n<p>Los educadores de los padres animan a que haya discusiones en la clase sobre las normas culturales que rodean asuntos de crianza Los padres tienen preguntas muchas veces sobre el habito de colecho y opciones de comida para el bebe. Las preguntas generan debates abiertos sobre estilos y tradiciones de crianza. Los educadores ofrecen opciones basadas sobre evidencias para el uso de los padres y para que los integren en sus tradiciones culturales y t\u00e9cnicas.<\/p>\n<h1>Respeto por la Cultura y la Tradici\u00f3n<\/h1>\n<p>La Casa del Carmen respeta y honra la cultura y la tradici\u00f3n de cada familia. No solo ofrece un lugar comunitario, sino tambi\u00e9n recursos, cuidado, y una conexi\u00f3n para mantener a las familias fuertes y pr\u00f3speras. El centro brinda servicios como una agencia de Catholic Social Services de la Archidi\u00f3cesis de Filadelfia para las diversas culturas presentes en Norte Filadelfia.<\/p>\n<p>La Casa del Carmen est\u00e1 abierto de lunes a viernes. Para registrarse para una clase de crianza o para obtener otros servicios, por favor llame a 267-331-2500.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En una tarde soleada y h\u00fameda en Julio, madres, padres, abuelos, y ni\u00f1os del Norte de Filadelfia se reunieron en la Casa del Carmen Centro de Servios para la Familia para el \u00abFestival de Verano\u00bb, una celebraci\u00f3n anual para las familias. El programa de Beautiful Beginnings de formaci\u00f3n para los padres en la Casa del Carmen acogi\u00f3 la tarde de comida y diversi\u00f3n. El acontecimiento fue un descanso bienvenido de eventos remotos y \u00abreuniones\u00bb digitales tan comunes a trav\u00e9s de la pandemia. Los vecinos disfrutaron de cosas favoritas de Philly: hoagies, pretzels suaves, y helado. Dice Jenny Munguia, BA, BSW, Maestra Prenatal y de Crianza en Casa del Carmen, \u201cEl festival de verano es una manera de reunir a la gente, y aliviar el estr\u00e9s de estar solo. Para que la gente puedan conocer a sus vecinos\u00bb. Educaci\u00f3n sobre Embarazo y Crianza Aislamiento social, y el estr\u00e9s que lo acompa\u00f1a, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[89],"tags":[],"class_list":["post-6322","post","type-post","status-publish","format-standard","hentry","category-sin-categorizar-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Apoyo para Padres e Hijos en la Casa del Carmen - Catholic Social Services<\/title>\n<meta name=\"description\" content=\"Padres e hijos encuentran apoyo en la Casa del Carmen, uno de los muchos ministerios de Catholic Social Services.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cssphiladelphia.org\/es\/apoyo-para-padres-e-hijos-en-la-casa-del-carmen\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Apoyo para Padres e Hijos en la Casa del Carmen - Catholic Social Services\" \/>\n<meta property=\"og:description\" content=\"Padres e hijos encuentran apoyo en la Casa del Carmen, uno de los muchos ministerios de Catholic Social Services.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cssphiladelphia.org\/es\/apoyo-para-padres-e-hijos-en-la-casa-del-carmen\/\" \/>\n<meta property=\"og:site_name\" content=\"Catholic Social Services\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-20T21:31:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cssphiladelphia.org\/wp-content\/uploads\/2022\/08\/pexels-julia-m-cameron-4145190-scaled.jpg\" \/>\n<meta name=\"author\" content=\"robert\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"robert\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cssphiladelphia.org\\\/es\\\/apoyo-para-padres-e-hijos-en-la-casa-del-carmen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cssphiladelphia.org\\\/es\\\/apoyo-para-padres-e-hijos-en-la-casa-del-carmen\\\/\"},\"author\":{\"name\":\"robert\",\"@id\":\"https:\\\/\\\/cssphiladelphia.org\\\/#\\\/schema\\\/person\\\/b1f4d28e01a95606bb38469bacaf39f4\"},\"headline\":\"Apoyo para Padres e Hijos en la Casa del Carmen\",\"datePublished\":\"2023-04-20T21:31:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cssphiladelphia.org\\\/es\\\/apoyo-para-padres-e-hijos-en-la-casa-del-carmen\\\/\"},\"wordCount\":916,\"image\":{\"@id\":\"https:\\\/\\\/cssphiladelphia.org\\\/es\\\/apoyo-para-padres-e-hijos-en-la-casa-del-carmen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cssphiladelphia.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/pexels-julia-m-cameron-4145190-scaled.jpg\",\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cssphiladelphia.org\\\/es\\\/apoyo-para-padres-e-hijos-en-la-casa-del-carmen\\\/\",\"url\":\"https:\\\/\\\/cssphiladelphia.org\\\/es\\\/apoyo-para-padres-e-hijos-en-la-casa-del-carmen\\\/\",\"name\":\"Apoyo para Padres e Hijos en la Casa del Carmen - Catholic Social Services\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cssphiladelphia.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cssphiladelphia.org\\\/es\\\/apoyo-para-padres-e-hijos-en-la-casa-del-carmen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cssphiladelphia.org\\\/es\\\/apoyo-para-padres-e-hijos-en-la-casa-del-carmen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cssphiladelphia.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/pexels-julia-m-cameron-4145190-scaled.jpg\",\"datePublished\":\"2023-04-20T21:31:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cssphiladelphia.org\\\/#\\\/schema\\\/person\\\/b1f4d28e01a95606bb38469bacaf39f4\"},\"description\":\"Padres e hijos encuentran apoyo en la Casa del Carmen, uno de los muchos ministerios de Catholic Social Services.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cssphiladelphia.org\\\/es\\\/apoyo-para-padres-e-hijos-en-la-casa-del-carmen\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cssphiladelphia.org\\\/es\\\/apoyo-para-padres-e-hijos-en-la-casa-del-carmen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/cssphiladelphia.org\\\/es\\\/apoyo-para-padres-e-hijos-en-la-casa-del-carmen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cssphiladelphia.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/pexels-julia-m-cameron-4145190-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/cssphiladelphia.org\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/pexels-julia-m-cameron-4145190-scaled.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cssphiladelphia.org\\\/es\\\/apoyo-para-padres-e-hijos-en-la-casa-del-carmen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/cssphiladelphia.org\\\/?lang=es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Apoyo para Padres e Hijos en la Casa del Carmen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cssphiladelphia.org\\\/#website\",\"url\":\"https:\\\/\\\/cssphiladelphia.org\\\/\",\"name\":\"Catholic Social Services\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cssphiladelphia.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cssphiladelphia.org\\\/#\\\/schema\\\/person\\\/b1f4d28e01a95606bb38469bacaf39f4\",\"name\":\"robert\",\"sameAs\":[\"http:\\\/\\\/localhost:10023\"],\"url\":\"https:\\\/\\\/cssphiladelphia.org\\\/es\\\/author\\\/robert\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Apoyo para Padres e Hijos en la Casa del Carmen - Catholic Social Services","description":"Padres e hijos encuentran apoyo en la Casa del Carmen, uno de los muchos ministerios de Catholic Social Services.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cssphiladelphia.org\/es\/apoyo-para-padres-e-hijos-en-la-casa-del-carmen\/","og_locale":"es_ES","og_type":"article","og_title":"Apoyo para Padres e Hijos en la Casa del Carmen - Catholic Social Services","og_description":"Padres e hijos encuentran apoyo en la Casa del Carmen, uno de los muchos ministerios de Catholic Social Services.","og_url":"https:\/\/cssphiladelphia.org\/es\/apoyo-para-padres-e-hijos-en-la-casa-del-carmen\/","og_site_name":"Catholic Social Services","article_published_time":"2023-04-20T21:31:24+00:00","og_image":[{"url":"https:\/\/cssphiladelphia.org\/wp-content\/uploads\/2022\/08\/pexels-julia-m-cameron-4145190-scaled.jpg","type":"","width":"","height":""}],"author":"robert","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"robert","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cssphiladelphia.org\/es\/apoyo-para-padres-e-hijos-en-la-casa-del-carmen\/#article","isPartOf":{"@id":"https:\/\/cssphiladelphia.org\/es\/apoyo-para-padres-e-hijos-en-la-casa-del-carmen\/"},"author":{"name":"robert","@id":"https:\/\/cssphiladelphia.org\/#\/schema\/person\/b1f4d28e01a95606bb38469bacaf39f4"},"headline":"Apoyo para Padres e Hijos en la Casa del Carmen","datePublished":"2023-04-20T21:31:24+00:00","mainEntityOfPage":{"@id":"https:\/\/cssphiladelphia.org\/es\/apoyo-para-padres-e-hijos-en-la-casa-del-carmen\/"},"wordCount":916,"image":{"@id":"https:\/\/cssphiladelphia.org\/es\/apoyo-para-padres-e-hijos-en-la-casa-del-carmen\/#primaryimage"},"thumbnailUrl":"https:\/\/cssphiladelphia.org\/wp-content\/uploads\/2022\/08\/pexels-julia-m-cameron-4145190-scaled.jpg","articleSection":["Sin categorizar"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/cssphiladelphia.org\/es\/apoyo-para-padres-e-hijos-en-la-casa-del-carmen\/","url":"https:\/\/cssphiladelphia.org\/es\/apoyo-para-padres-e-hijos-en-la-casa-del-carmen\/","name":"Apoyo para Padres e Hijos en la Casa del Carmen - Catholic Social Services","isPartOf":{"@id":"https:\/\/cssphiladelphia.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cssphiladelphia.org\/es\/apoyo-para-padres-e-hijos-en-la-casa-del-carmen\/#primaryimage"},"image":{"@id":"https:\/\/cssphiladelphia.org\/es\/apoyo-para-padres-e-hijos-en-la-casa-del-carmen\/#primaryimage"},"thumbnailUrl":"https:\/\/cssphiladelphia.org\/wp-content\/uploads\/2022\/08\/pexels-julia-m-cameron-4145190-scaled.jpg","datePublished":"2023-04-20T21:31:24+00:00","author":{"@id":"https:\/\/cssphiladelphia.org\/#\/schema\/person\/b1f4d28e01a95606bb38469bacaf39f4"},"description":"Padres e hijos encuentran apoyo en la Casa del Carmen, uno de los muchos ministerios de Catholic Social Services.","breadcrumb":{"@id":"https:\/\/cssphiladelphia.org\/es\/apoyo-para-padres-e-hijos-en-la-casa-del-carmen\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cssphiladelphia.org\/es\/apoyo-para-padres-e-hijos-en-la-casa-del-carmen\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/cssphiladelphia.org\/es\/apoyo-para-padres-e-hijos-en-la-casa-del-carmen\/#primaryimage","url":"https:\/\/cssphiladelphia.org\/wp-content\/uploads\/2022\/08\/pexels-julia-m-cameron-4145190-scaled.jpg","contentUrl":"https:\/\/cssphiladelphia.org\/wp-content\/uploads\/2022\/08\/pexels-julia-m-cameron-4145190-scaled.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cssphiladelphia.org\/es\/apoyo-para-padres-e-hijos-en-la-casa-del-carmen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/cssphiladelphia.org\/?lang=es"},{"@type":"ListItem","position":2,"name":"Apoyo para Padres e Hijos en la Casa del Carmen"}]},{"@type":"WebSite","@id":"https:\/\/cssphiladelphia.org\/#website","url":"https:\/\/cssphiladelphia.org\/","name":"Catholic Social Services","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cssphiladelphia.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/cssphiladelphia.org\/#\/schema\/person\/b1f4d28e01a95606bb38469bacaf39f4","name":"robert","sameAs":["http:\/\/localhost:10023"],"url":"https:\/\/cssphiladelphia.org\/es\/author\/robert\/"}]}},"_links":{"self":[{"href":"https:\/\/cssphiladelphia.org\/es\/wp-json\/wp\/v2\/posts\/6322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cssphiladelphia.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cssphiladelphia.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cssphiladelphia.org\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cssphiladelphia.org\/es\/wp-json\/wp\/v2\/comments?post=6322"}],"version-history":[{"count":0,"href":"https:\/\/cssphiladelphia.org\/es\/wp-json\/wp\/v2\/posts\/6322\/revisions"}],"wp:attachment":[{"href":"https:\/\/cssphiladelphia.org\/es\/wp-json\/wp\/v2\/media?parent=6322"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cssphiladelphia.org\/es\/wp-json\/wp\/v2\/categories?post=6322"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cssphiladelphia.org\/es\/wp-json\/wp\/v2\/tags?post=6322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}